{"id":3359,"date":"2019-11-22T09:22:36","date_gmt":"2019-11-22T09:22:36","guid":{"rendered":"https:\/\/www.giftsworldexpo.com\/?post_type=media_coverage&amp;p=3359"},"modified":"2019-11-22T09:22:36","modified_gmt":"2019-11-22T09:22:36","slug":"ndtv","status":"publish","type":"media_coverage","link":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/","title":{"rendered":"www.ndtv.com\/india"},"content":{"rendered":"","protected":false},"featured_media":3360,"template":"","class_list":["post-3359","media_coverage","type-media_coverage","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>www.ndtv.com\/india - Gifts World Expo Kolkata - Largest Exhibition for Gifts Sourcing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"www.ndtv.com\/india - Gifts World Expo Kolkata - Largest Exhibition for Gifts Sourcing\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/\" \/>\n<meta property=\"og:site_name\" content=\"Gifts World Expo Kolkata - Largest Exhibition for Gifts Sourcing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/giftsworldexpo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giftsworldexpo.com\/kol\/wp-content\/uploads\/2019\/11\/ndtv-india.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@giftsworldexpo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/media_coverage\\\/ndtv\\\/\",\"url\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/media_coverage\\\/ndtv\\\/\",\"name\":\"www.ndtv.com\\\/india - Gifts World Expo Kolkata - Largest Exhibition for Gifts Sourcing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/media_coverage\\\/ndtv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/media_coverage\\\/ndtv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ndtv-india.jpg\",\"datePublished\":\"2019-11-22T09:22:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/media_coverage\\\/ndtv\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/media_coverage\\\/ndtv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/media_coverage\\\/ndtv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ndtv-india.jpg\",\"contentUrl\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ndtv-india.jpg\",\"width\":800,\"height\":480,\"caption\":\"no alt text\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/media_coverage\\\/ndtv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"www.ndtv.com\\\/india\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/#website\",\"url\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/\",\"name\":\"Gifts World Expo - Eastern India's Largest Exhibition for Gifts Sourcing\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/#organization\",\"name\":\"Gifts World Expo - Eastern India's Largest Exhibition for Gifts Sourcing\",\"url\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-1.png\",\"width\":300,\"height\":295,\"caption\":\"Gifts World Expo - Eastern India's Largest Exhibition for Gifts Sourcing\"},\"image\":{\"@id\":\"https:\\\/\\\/giftsworldexpo.com\\\/kol\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/giftsworldexpo\",\"https:\\\/\\\/x.com\\\/giftsworldexpo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"www.ndtv.com\/india - Gifts World Expo Kolkata - Largest Exhibition for Gifts Sourcing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/","og_locale":"en_US","og_type":"article","og_title":"www.ndtv.com\/india - Gifts World Expo Kolkata - Largest Exhibition for Gifts Sourcing","og_url":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/","og_site_name":"Gifts World Expo Kolkata - Largest Exhibition for Gifts Sourcing","article_publisher":"https:\/\/www.facebook.com\/giftsworldexpo","og_image":[{"width":800,"height":480,"url":"https:\/\/giftsworldexpo.com\/kol\/wp-content\/uploads\/2019\/11\/ndtv-india.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@giftsworldexpo","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/","url":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/","name":"www.ndtv.com\/india - Gifts World Expo Kolkata - Largest Exhibition for Gifts Sourcing","isPartOf":{"@id":"https:\/\/giftsworldexpo.com\/kol\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/#primaryimage"},"image":{"@id":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/#primaryimage"},"thumbnailUrl":"https:\/\/giftsworldexpo.com\/kol\/wp-content\/uploads\/2019\/11\/ndtv-india.jpg","datePublished":"2019-11-22T09:22:36+00:00","breadcrumb":{"@id":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/#primaryimage","url":"https:\/\/giftsworldexpo.com\/kol\/wp-content\/uploads\/2019\/11\/ndtv-india.jpg","contentUrl":"https:\/\/giftsworldexpo.com\/kol\/wp-content\/uploads\/2019\/11\/ndtv-india.jpg","width":800,"height":480,"caption":"no alt text"},{"@type":"BreadcrumbList","@id":"https:\/\/giftsworldexpo.com\/kol\/media_coverage\/ndtv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giftsworldexpo.com\/kol\/"},{"@type":"ListItem","position":2,"name":"www.ndtv.com\/india"}]},{"@type":"WebSite","@id":"https:\/\/giftsworldexpo.com\/kol\/#website","url":"https:\/\/giftsworldexpo.com\/kol\/","name":"Gifts World Expo - Eastern India's Largest Exhibition for Gifts Sourcing","description":"","publisher":{"@id":"https:\/\/giftsworldexpo.com\/kol\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giftsworldexpo.com\/kol\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/giftsworldexpo.com\/kol\/#organization","name":"Gifts World Expo - Eastern India's Largest Exhibition for Gifts Sourcing","url":"https:\/\/giftsworldexpo.com\/kol\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giftsworldexpo.com\/kol\/#\/schema\/logo\/image\/","url":"https:\/\/giftsworldexpo.com\/kol\/wp-content\/uploads\/2026\/01\/logo-1.png","contentUrl":"https:\/\/giftsworldexpo.com\/kol\/wp-content\/uploads\/2026\/01\/logo-1.png","width":300,"height":295,"caption":"Gifts World Expo - Eastern India's Largest Exhibition for Gifts Sourcing"},"image":{"@id":"https:\/\/giftsworldexpo.com\/kol\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/giftsworldexpo","https:\/\/x.com\/giftsworldexpo"]}]}},"_links":{"self":[{"href":"https:\/\/giftsworldexpo.com\/kol\/wp-json\/wp\/v2\/media_coverage\/3359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giftsworldexpo.com\/kol\/wp-json\/wp\/v2\/media_coverage"}],"about":[{"href":"https:\/\/giftsworldexpo.com\/kol\/wp-json\/wp\/v2\/types\/media_coverage"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giftsworldexpo.com\/kol\/wp-json\/wp\/v2\/media\/3360"}],"wp:attachment":[{"href":"https:\/\/giftsworldexpo.com\/kol\/wp-json\/wp\/v2\/media?parent=3359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}